{"id":11042,"count":1,"description":"","link":"https:\/\/zidrave.net\/index.php\/tag\/trim-linux\/","name":"trim linux","slug":"trim-linux","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/zidrave.net\/index.php\/wp-json\/wp\/v2\/tags\/11042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zidrave.net\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/zidrave.net\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/zidrave.net\/index.php\/wp-json\/wp\/v2\/posts?tags=11042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}